{"id":527,"date":"2026-04-24T13:41:04","date_gmt":"2026-04-24T11:41:04","guid":{"rendered":"https:\/\/zeenas.de\/wordpress\/?p=527"},"modified":"2026-04-24T13:44:57","modified_gmt":"2026-04-24T11:44:57","slug":"2-716-freitagsfueller","status":"publish","type":"post","link":"https:\/\/zeenas.de\/wordpress\/2026\/04\/24\/2-716-freitagsfueller\/","title":{"rendered":"2.716 &#8211; Freitagsf\u00fcller"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jetzt, da ich wieder einen Blog schreibe, habe ich mich an die Tradition des &#8222;<a href=\"https:\/\/scrapimpulse.com\/2026\/04\/gedanken-zur-woche-freitagstipps-freitagsfueller-871\/\">Freitags-F\u00fcllers<\/a>&#8220; erinnert und siehe da &#8211; es gibt ihn noch! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es werden dort L\u00fcckentexte bereitgestellt, die man mit eigenen Gedanken und Ideen f\u00fcllen kann. Gern greife ich die Tradition heute wieder auf und beteilige mich. Es ist auch eine gute Idee, dort mal zu st\u00f6bern, ich finde dann h\u00e4ufig andere lesenswerte Blogs, die ich noch nicht kannte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1.&nbsp; &nbsp;Was ist&nbsp;<strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">soziale Gerechtigkeit? Diese politische Diskussion wird in Angesicht der knapper werdenden finanziellen Mittel kurz-, mittel- und in Bezug auf die Rentendiskussion auch langfristig immer wieder er\u00f6rtert werden m\u00fcssen.<\/mark><\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. &nbsp; &nbsp;<strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">Am meisten verunsichert bin ich einen Tag vor dem Termin<\/mark><\/em><\/strong>&nbsp; beim Zahnarzt, <strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">wenn ich da erst mal bin, ist die Behandlung nicht halb so schlimm, wie ich sie mir vorgestellt habe<\/mark><\/em><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.&nbsp; Es k\u00f6nnte sein, <strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">dass ich tats\u00e4chlich schaffe, sowohl meinen Wollvorrat als auch andere Gegenst\u00e4nde stark zu reduzieren in Anbetracht der Tatsache, dass ich nach Eintritt in die Rente weniger Platz wegen einer kleineren Wohnung haben werde (kleiner hei\u00dft hier: nicht mehr 170 m\u00b2 f\u00fcr eine Drei-Zimmer-Wohnung auf dem Land, wo Platz nicht viel kostet) .<\/mark><\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. <strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">Manchmal mache ich mir unn\u00f6tige Gedanken \u00fcber eigentlich unwichtige Dinge, zum Beispiel dar\u00fcber, ob die Wolle f\u00fcr ein bestimmtes Projekt klappt, ob meine Planungen aufgehen, ob Treffen zustande kommen<\/mark><\/em><\/strong> und es klappt <strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">dann doch meist v\u00f6llig unspektakul\u00e4r<\/mark><\/em><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.\u00a0 Meine letzte Autofahrt\u00a0 <strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">war heute Vormittag, um ein KfZ umzumelden, nachdem ich vor zwei Tagen das andere KfZ umgemeldet habe, denn aus versicherungstechnischen Gr\u00fcnden ist es kostenreduzierend, wenn das &#8222;teurere&#8220; Auto auf <a href=\"https:\/\/zeenas.de\/wordpress\/abkuerzungen\/\">mP<\/a> l\u00e4uft, er hat einen h\u00f6heren Schadenfreiheitsrabatt als ich.<\/mark><\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. <strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">Ich liebe den Geschmack von <\/mark><\/em><\/strong> Erdbeeren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7. Was das Wochenende angeht, heute Abend freue ich mich auf <strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">leckeres Essen kochen und sp\u00e4ter essen, es soll Nudeln mit Gorgonzola-Sauce geben<\/mark><\/em><\/strong>, morgen habe ich geplant, <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\"><strong><em>hier einige Baustellen zu beenden, ein kleines Regal m\u00f6chte noch gebaut werden und einige Dinge sollen verr\u00e4umt werden<\/em> <\/strong><\/mark>und Sonntag m\u00f6chte ich <strong><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-accent-2-color\">vielleicht in die Therme gehen, wenn ich mit meinen Samstags-Aufgaben fertig geworden bin und den Blog-Beitrag f\u00fcr die Sonntags-Ver\u00f6ffentlichung fertig habe (es ist wieder <a href=\"https:\/\/zeenas.de\/wordpress\/abkuerzungen\/\">#FJKA<\/a> beim Me-Made-Mittwoch)<\/mark><\/em><\/strong> !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und nun gehe ich mal schauen, was die anderen so geschrieben haben. Euch allen ein sch\u00f6nes Wochenende, hier lesen wir uns am Sonntag wieder. Habt bis dahin eine sch\u00f6ne Zeit. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jetzt, da ich wieder einen Blog schreibe, habe ich mich an die Tradition des &#8222;Freitags-F\u00fcllers&#8220; erinnert und siehe da &#8211; es gibt ihn noch! Es werden dort L\u00fcckentexte bereitgestellt, die man mit eigenen Gedanken und Ideen f\u00fcllen kann. Gern greife ich die Tradition heute wieder auf und beteilige mich. Es ist auch eine gute Idee, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[142],"tags":[],"class_list":["post-527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-freitagsfueller"],"jetpack_featured_media_url":"https:\/\/zeenas.de\/wordpress\/wp-content\/uploads\/2026\/04\/Freitags-Fueller.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/posts\/527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/comments?post=527"}],"version-history":[{"count":7,"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/posts\/527\/revisions"}],"predecessor-version":[{"id":535,"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/posts\/527\/revisions\/535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/media\/530"}],"wp:attachment":[{"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/media?parent=527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/categories?post=527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zeenas.de\/wordpress\/wp-json\/wp\/v2\/tags?post=527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}